{"id":869,"date":"2020-03-12T10:55:15","date_gmt":"2020-03-12T10:55:15","guid":{"rendered":"https:\/\/www.360nrs.com\/blog\/?p=869"},"modified":"2025-05-29T15:29:19","modified_gmt":"2025-05-29T15:29:19","slug":"email-marketing-fechas-especiales","status":"publish","type":"post","link":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/","title":{"rendered":"Email Marketing para fechas especiales"},"content":{"rendered":"\n<p>Se acerca -otra vez- una de las fechas que aparece subrayada en todos los calendarios de marketing e-commerce: El d\u00eda del Padre. Por lo que, trazar una campa\u00f1a de <strong><a href=\"https:\/\/www.360nrs.com\/mails-masivos\/email-marketing\">Email Marketing<\/a><\/strong> ser\u00e1 la v\u00eda perfecta para promocionar servicios y productos para este d\u00eda.<\/p>\n\n\n\n<p>As\u00ed, el 19 de marzo se convierte en otra gran oportunidad para que las empresas aumenten sus ventas. \u00a0Y el <strong><a href=\"https:\/\/www.360nrs.com\/mails-masivos\/email-marketing\">Email Marketing<\/a><\/strong> en el canal id\u00f3neo para llevar a cabo la campa\u00f1a. \u00a0Adem\u00e1s, gracias al email marketing podr\u00e1s establecer relaciones con clientes actuales y potenciales, y generar relaciones a largo plazo.<\/p>\n\n\n\n<p>Por tanto, en este art\u00edculo te ense\u00f1amos c\u00f3mo realizar una campa\u00f1a de <a href=\"https:\/\/www.360nrs.com\/mailing\">mailing masivos<\/a> de \u00e9xito para el d\u00eda del Padre y fechas especiales. \u00a1Toma nota!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color\">9 consejos para una campa\u00f1a de <a href=\"https:\/\/www.360nrs.com\/mails-masivos\/email-marketing\">Email Marketing<\/a> de \u00e9xito:<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Titulo llamativo, breve y directo<\/strong>. El t\u00edtulo ser\u00e1 lo primero que lea tu receptor, por lo que ser\u00e1 tan importante como el contenido. No debes dejar de lado este aspecto, ya que ser\u00e1 decisivo para captar el inter\u00e9s de tu suscriptor o cliente. <\/li>\n\n\n\n<li>  <strong>Identifica tu email<\/strong>: no te olvides de poner el logo de tu empresa en el encabezado del correo e indexar el enlace \u201cversi\u00f3n web\u201d por si el receptor tiene problemas a la hora de visualizar el contenido.  <\/li>\n\n\n\n<li> <strong>No te pases con la extensi\u00f3n del texto: <\/strong>tu objetivo no ser\u00e1 rellenar la <em>newsletter<\/em> con el m\u00e1ximo contenido posible, sino a\u00f1adir solo el contenido relevante para el lector. Recuerda que menos es siempre m\u00e1s.   Y no te olvides de, <strong>revisa el texto:<\/strong> seg\u00fan un estudio llevado a cabo por la <a href=\"https:\/\/www.bbc.com\/news\">BBC<\/a> los errores ortogr\u00e1ficos influyen negativamente en las ventas. Por lo que ser\u00e1 fundamental que revises tu texto antes de lanzar la campa\u00f1a. <\/li>\n\n\n\n<li> <strong>Siempre un Call to Action:<\/strong> a\u00f1ade un bot\u00f3n que desencadene en una acci\u00f3n. De esta forma, derivar\u00e1 al cliente potencial a la p\u00e1gina web donde encontrar\u00e1 la promoci\u00f3n de tu <em>e-commerce,<\/em> registro o contenido descargable. <\/li>\n\n\n\n<li> <strong>Cuida las im\u00e1genes:<\/strong> es importante que tu correo contenga im\u00e1genes que reafirmen el contenido o aporten m\u00e1s informaci\u00f3n. Solo deber\u00e1s tener en cuenta no inundar el email con im\u00e1genes. Si quieres hacer tu plantilla m\u00e1s atractiva te recomendamos utilizar iconograf\u00eda. De igual forma, ten cuidado en el tama\u00f1o y calidad de las im\u00e1genes ya que, algunos gestores bloquean el email si el formato es demasiado grande.<\/li>\n\n\n\n<li> <strong>A\u00f1ade botones sociales:<\/strong> te recomendamos siempre a\u00f1adir al final del texto los botones de tus redes sociales, ya que ayudar\u00e1 a que el receptor conozca mejor tu empresa, y facilitar\u00e1 que el contenido enviado sea compartido.     <\/li>\n\n\n\n<li> <strong>Datos de la empresa:<\/strong> ser\u00e1 igual de importante que indiques los datos de tu empresa, as\u00ed como modos de contacto en el pie del correo comercial. Aparte de dar un aspecto m\u00e1s profesional y generar confianza, te servir\u00e1 para que el receptor pueda contactar contigo por diferentes v\u00edas.  <\/li>\n\n\n\n<li> <strong>Enlace de baja:<\/strong> deber\u00e1s de a\u00f1adir, ya sea al principio o al final, un bot\u00f3n de baja. Es fundamental, para una buena pr\u00e1ctica, que ofrezcas al usuario la posibilidad de dar de baja la suscripci\u00f3n. <\/li>\n\n\n\n<li> <strong>Realiza pruebas: <\/strong>antes de enviar tu correo electr\u00f3nico, te recomendamos que realices un env\u00edo de prueba para revisar todos los criterios anteriores de forma m\u00e1s minuciosa, y comprobar que se lee bien en cualquier dispositivo. <\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"494\" height=\"1024\" src=\"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/9-tips-de-email-marketing-494x1024.png\" alt=\"9 Tips de Email Marketing\" class=\"wp-image-872\"\/><figcaption class=\"wp-element-caption\">9 Consejos para una campa\u00f1a de Email Marketing de \u00e9xito &#8211; 360NRS<\/figcaption><\/figure><\/div>\n\n\n<p>Siguiendo estos consejos\u2026 solo te queda ponerte manos a la obra y lanzar tu campa\u00f1a especial del D\u00eda del Padre. Para ello, en nuestra plataforma puedes encontrar diferentes plantillas sobre esta tem\u00e1tica, que podr\u00e1s personalizar a tu gusto. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00a1Enviar miles de emails con una plantilla profesional nunca fue tan f\u00e1cil! <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se acerca -otra vez- una de las fechas que aparece subrayada en todos los calendarios de marketing e-commerce: El d\u00eda del Padre. Por lo que, trazar una campa\u00f1a de Email Marketing ser\u00e1 la v\u00eda perfecta para promocionar servicios y productos para este d\u00eda. As\u00ed, el 19 de marzo se convierte en otra gran oportunidad para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":876,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[153,51],"class_list":["post-869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-email","tag-calendario-de-marketing","tag-email-marketing"],"featured_image_src":{"landsacpe":["https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632-1140x445.jpg",1140,445,true],"list":["https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632-463x348.jpg",463,348,true],"medium":["https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632-400x224.jpg",400,224,true],"full":["https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg",1483,829,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Email Marketing para fechas especiales | 360NRS<\/title>\n<meta name=\"description\" content=\"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Email Marketing para fechas especiales | 360NRS\" \/>\n<meta property=\"og:description\" content=\"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/\" \/>\n<meta property=\"og:site_name\" content=\"360NRS - Plataforma de Marketing Multicanal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/360nrs\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T10:55:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T15:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1483\" \/>\n\t<meta property=\"og:image:height\" content=\"829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"360NRS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"360NRS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/\"},\"author\":{\"name\":\"360NRS\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef52fb9eb53e478309b9fda6421d040c\"},\"headline\":\"Email Marketing para fechas especiales\",\"datePublished\":\"2020-03-12T10:55:15+00:00\",\"dateModified\":\"2025-05-29T15:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/\"},\"wordCount\":660,\"publisher\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/632.jpg\",\"keywords\":[\"Calendario de Marketing\",\"Email Marketing\"],\"articleSection\":[\"Email Marketing\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/\",\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/\",\"name\":\"Email Marketing para fechas especiales | 360NRS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/632.jpg\",\"datePublished\":\"2020-03-12T10:55:15+00:00\",\"dateModified\":\"2025-05-29T15:29:19+00:00\",\"description\":\"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/632.jpg\",\"contentUrl\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/632.jpg\",\"width\":1483,\"height\":829},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email-marketing-fechas-especiales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"BLOG 360NRS\",\"item\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Email Marketing\",\"item\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/email\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Email Marketing para fechas especiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/\",\"name\":\"360NRS - Plataforma de Marketing Multicanal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#organization\"},\"alternateName\":\"Marketing Multicanal 360NRS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#organization\",\"name\":\"360NRS\",\"alternateName\":\"Marketing Multicanal 360NRS\",\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/360-blog-ico.png\",\"contentUrl\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/360-blog-ico.png\",\"width\":512,\"height\":512,\"caption\":\"360NRS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/360nrs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/360nrs-by-nrs-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@360nrs5\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef52fb9eb53e478309b9fda6421d040c\",\"name\":\"360NRS\",\"description\":\"Plataforma CPaaS Marketing Digital Multicanal. 360NRS somos tu plataforma CPaaS de Marketing Multicanal lider en env\u00edo masivo de SMS, mailing, WhatsApp, IVR y llamadas automatizadas.\",\"sameAs\":[\"https:\\\/\\\/www.360nrs.com\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/360nrs-by-nrs-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@360nrs5\"],\"url\":\"https:\\\/\\\/www.360nrs.com\\\/blog\\\/author\\\/360nrs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Email Marketing para fechas especiales | 360NRS","description":"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/","og_locale":"es_ES","og_type":"article","og_title":"Email Marketing para fechas especiales | 360NRS","og_description":"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.","og_url":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/","og_site_name":"360NRS - Plataforma de Marketing Multicanal","article_publisher":"https:\/\/es-es.facebook.com\/360nrs\/","article_published_time":"2020-03-12T10:55:15+00:00","article_modified_time":"2025-05-29T15:29:19+00:00","og_image":[{"width":1483,"height":829,"url":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg","type":"image\/jpeg"}],"author":"360NRS","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"360NRS","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#article","isPartOf":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/"},"author":{"name":"360NRS","@id":"https:\/\/www.360nrs.com\/blog\/#\/schema\/person\/ef52fb9eb53e478309b9fda6421d040c"},"headline":"Email Marketing para fechas especiales","datePublished":"2020-03-12T10:55:15+00:00","dateModified":"2025-05-29T15:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/"},"wordCount":660,"publisher":{"@id":"https:\/\/www.360nrs.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg","keywords":["Calendario de Marketing","Email Marketing"],"articleSection":["Email Marketing"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/","url":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/","name":"Email Marketing para fechas especiales | 360NRS","isPartOf":{"@id":"https:\/\/www.360nrs.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#primaryimage"},"image":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg","datePublished":"2020-03-12T10:55:15+00:00","dateModified":"2025-05-29T15:29:19+00:00","description":"Las fechas especiales se convierten en una gran oportunidad para aumentar las ventas y el Email Marketing en la v\u00eda perfecta de comunicaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#primaryimage","url":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg","contentUrl":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2020\/03\/632.jpg","width":1483,"height":829},{"@type":"BreadcrumbList","@id":"https:\/\/www.360nrs.com\/blog\/email-marketing-fechas-especiales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"BLOG 360NRS","item":"https:\/\/www.360nrs.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Email Marketing","item":"https:\/\/www.360nrs.com\/blog\/email\/"},{"@type":"ListItem","position":3,"name":"Email Marketing para fechas especiales"}]},{"@type":"WebSite","@id":"https:\/\/www.360nrs.com\/blog\/#website","url":"https:\/\/www.360nrs.com\/blog\/","name":"360NRS - Plataforma de Marketing Multicanal","description":"","publisher":{"@id":"https:\/\/www.360nrs.com\/blog\/#organization"},"alternateName":"Marketing Multicanal 360NRS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.360nrs.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.360nrs.com\/blog\/#organization","name":"360NRS","alternateName":"Marketing Multicanal 360NRS","url":"https:\/\/www.360nrs.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.360nrs.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2022\/03\/360-blog-ico.png","contentUrl":"https:\/\/www.360nrs.com\/blog\/wp-content\/uploads\/2022\/03\/360-blog-ico.png","width":512,"height":512,"caption":"360NRS"},"image":{"@id":"https:\/\/www.360nrs.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/360nrs\/","https:\/\/www.linkedin.com\/showcase\/360nrs-by-nrs-group\/","https:\/\/www.youtube.com\/@360nrs5"]},{"@type":"Person","@id":"https:\/\/www.360nrs.com\/blog\/#\/schema\/person\/ef52fb9eb53e478309b9fda6421d040c","name":"360NRS","description":"Plataforma CPaaS Marketing Digital Multicanal. 360NRS somos tu plataforma CPaaS de Marketing Multicanal lider en env\u00edo masivo de SMS, mailing, WhatsApp, IVR y llamadas automatizadas.","sameAs":["https:\/\/www.360nrs.com","https:\/\/www.linkedin.com\/showcase\/360nrs-by-nrs-group\/","https:\/\/www.youtube.com\/@360nrs5"],"url":"https:\/\/www.360nrs.com\/blog\/author\/360nrs\/"}]}},"_links":{"self":[{"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":11,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"predecessor-version":[{"id":5811,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/posts\/869\/revisions\/5811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/media\/876"}],"wp:attachment":[{"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.360nrs.com\/blog\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}